{"id":30,"date":"2025-12-14T17:35:38","date_gmt":"2025-12-14T15:35:38","guid":{"rendered":"https:\/\/deglavarezidence.lv\/?page_id=30"},"modified":"2026-06-09T16:03:03","modified_gmt":"2026-06-09T13:03:03","slug":"sakums","status":"publish","type":"page","link":"https:\/\/deglavarezidence.lv\/en\/","title":{"rendered":"Home"},"content":{"rendered":"<section class=\"bde-section-30-855 bde-section silky-reveal\" data-parallax=\"true\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-columns-30-856 bde-columns\"><div class=\"bde-column-30-857 bde-column\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-30-858 bde-div\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-30-859 bde-heading stagger-item main-hero-heading\">\nDeglava Painters Residence \u2014 <i>where your life unfolds a work of art.<\/i>\n<\/h2>\n<\/div><div class=\"bde-div-30-860 bde-div\">\n  \n  \n\t\n\n\n\n<p class=\"bde-text-30-861 bde-text stagger-item\">\nFully finished apartments with A energy efficiency. Ready to move in today. Price from <b>67 821 \u20ac<\/b>\n<\/p><div class=\"bde-div-30-862 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-button-30-863 bde-button stagger-item\">\n        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"\/en\/choose-an-apartment\/\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Choose an apartment<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div><div class=\"bde-button-30-864 bde-button stagger-item\">\n        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--secondary bde-button__button\" href=\"#piesaki_apskati\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Book a visit<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"bde-column-30-865 bde-column\">\n  \n  \n\t\n\n\n\n<div class=\"bde-logo-list-30-866 bde-logo-list stagger-item un-image-carousel-container\">\n\n  <div class=\"un-logo-bar__marquee-content carousel-type__stop-on-hover\">\n                            <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1.jpg\" width=\"1536\" height=\"1920\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1.jpg 1536w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-819x1024.jpg 819w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-768x960.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-1229x1536.jpg 1229w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1.jpg\" width=\"1119\" height=\"1400\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1.jpg 1119w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-818x1024.jpg 818w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-768x961.jpg 768w\" sizes=\"auto, (max-width: 1119px) 100vw, 1119px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1.jpg\" width=\"1330\" height=\"1663\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1.jpg 1330w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-819x1024.jpg 819w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-768x960.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-1228x1536.jpg 1228w\" sizes=\"auto, (max-width: 1330px) 100vw, 1330px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1.jpg\" width=\"1536\" height=\"1920\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1.jpg 1536w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-819x1024.jpg 819w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-768x960.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-1229x1536.jpg 1229w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1.jpg\" width=\"1119\" height=\"1400\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1.jpg 1119w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-818x1024.jpg 818w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-768x961.jpg 768w\" sizes=\"auto, (max-width: 1119px) 100vw, 1119px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1.jpg\" width=\"1330\" height=\"1663\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1.jpg 1330w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-819x1024.jpg 819w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-768x960.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-1228x1536.jpg 1228w\" sizes=\"auto, (max-width: 1330px) 100vw, 1330px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1.jpg\" width=\"1536\" height=\"1920\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1.jpg 1536w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-819x1024.jpg 819w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-768x960.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-1229x1536.jpg 1229w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1.jpg\" width=\"1119\" height=\"1400\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1.jpg 1119w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-818x1024.jpg 818w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-768x961.jpg 768w\" sizes=\"auto, (max-width: 1119px) 100vw, 1119px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1.jpg\" width=\"1330\" height=\"1663\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1.jpg 1330w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-819x1024.jpg 819w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-768x960.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-1228x1536.jpg 1228w\" sizes=\"auto, (max-width: 1330px) 100vw, 1330px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1.jpg\" width=\"1536\" height=\"1920\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1.jpg 1536w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-819x1024.jpg 819w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-768x960.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-1229x1536.jpg 1229w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1.jpg\" width=\"1119\" height=\"1400\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1.jpg 1119w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-818x1024.jpg 818w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-768x961.jpg 768w\" sizes=\"auto, (max-width: 1119px) 100vw, 1119px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1.jpg\" width=\"1330\" height=\"1663\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1.jpg 1330w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-819x1024.jpg 819w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-768x960.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-1228x1536.jpg 1228w\" sizes=\"auto, (max-width: 1330px) 100vw, 1330px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1.jpg\" width=\"1536\" height=\"1920\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1.jpg 1536w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-819x1024.jpg 819w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-768x960.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-1229x1536.jpg 1229w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1.jpg\" width=\"1119\" height=\"1400\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1.jpg 1119w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-818x1024.jpg 818w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-768x961.jpg 768w\" sizes=\"auto, (max-width: 1119px) 100vw, 1119px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1.jpg\" width=\"1330\" height=\"1663\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1.jpg 1330w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-819x1024.jpg 819w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-768x960.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-1228x1536.jpg 1228w\" sizes=\"auto, (max-width: 1330px) 100vw, 1330px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1.jpg\" width=\"1536\" height=\"1920\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1.jpg 1536w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-819x1024.jpg 819w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-768x960.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-90-1-1229x1536.jpg 1229w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1.jpg\" width=\"1119\" height=\"1400\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1.jpg 1119w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-818x1024.jpg 818w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Dali-1-768x961.jpg 768w\" sizes=\"auto, (max-width: 1119px) 100vw, 1119px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1.jpg\" width=\"1330\" height=\"1663\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1.jpg 1330w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-240x300.jpg 240w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-819x1024.jpg 819w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-768x960.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-29-1-1228x1536.jpg 1228w\" sizes=\"auto, (max-width: 1330px) 100vw, 1330px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n        <\/div>\n                      <\/div>\n<\/div>\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-30-867 bde-section silky-reveal\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-grid-30-868 bde-grid\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-30-869 bde-div\">\n  \n  \n\t\n\n\n\n<p class=\"bde-text-30-1495 bde-text stagger-item\">\nAbout the project\n<\/p><div class=\"bde-div-30-871 bde-div\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-30-1013 bde-heading stagger-item\">\nWelcome home,\n<\/h2><div class=\"bde-text-30-872 bde-text stagger-item\">\nWe have painted a new picture in the heart of Plavnieki - <b>Deglava Painters Residence<\/b> - a modern new project.<br><br>The new project provides everything that is needed for a modern home - a choice of apartments of different sizes, energy-efficient solutions, spacious and well-thought-out layouts, and an ideal location in P\u013cavnieki.\n<\/div><div class=\"bde-text-30-873 bde-text stagger-item\">\n5 buildings have already been built, with a total of 365 ready apartments. Now it's time for the final stage, and we are pleased to start selling the final two buildings of the project, the Deglava Painters' Residence.\n<\/div><div class=\"bde-button-30-874 bde-button stagger-item\">\n        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"\/en\/choose-an-apartment\/\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Choose an apartment<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div><div class=\"bde-div-30-875 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-30-876 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-simple-counter-30-877 bde-simple-counter stagger-item\">\n<div class=\"bde-simple-counter__wrapper\">\n  <p class=\"bde-simple-counter__number bde-h6\">\n    <span class=\"bde-simple-counter__prefix\"><\/span>\n    <span class=\"bde-simple-counter__digit js-digit\"><\/span>\n    <span class=\"bde-simple-counter__suffix\"><\/span>\n  <\/p>\n  <\/div>\n\n<\/div><div class=\"bde-text-30-878 bde-text stagger-item\">\nBuildings constructed\n<\/div>\n<\/div><div class=\"bde-div-30-879 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-simple-counter-30-880 bde-simple-counter stagger-item\">\n<div class=\"bde-simple-counter__wrapper\">\n  <p class=\"bde-simple-counter__number bde-h6\">\n    <span class=\"bde-simple-counter__prefix\"><\/span>\n    <span class=\"bde-simple-counter__digit js-digit\"><\/span>\n    <span class=\"bde-simple-counter__suffix\">+<\/span>\n  <\/p>\n  <\/div>\n\n<\/div><div class=\"bde-text-30-881 bde-text stagger-item\">\nSold apartments\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"bde-div-30-882 bde-div\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-30-883 bde-image2 img-reveal\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-72.jpg\" loading=\"lazy\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-72.jpg 1600w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-72-300x200.jpg 300w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-72-1024x683.jpg 1024w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-72-768x512.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-rezidence-72-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" alt=\"Deglava Rezidence - new apartments in Riga\"><div class=\"bde-grid-30-884 bde-grid\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-30-885 bde-image2 img-reveal\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/IMG_7999.jpg\" loading=\"lazy\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/IMG_7999.jpg 1920w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/IMG_7999-300x200.jpg 300w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/IMG_7999-1024x683.jpg 1024w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/IMG_7999-768x512.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/IMG_7999-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" alt=\"Deglava Rezidence - new apartments in Riga\"><img decoding=\"async\" class=\"bde-image2-30-1012 bde-image2 img-reveal\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-26.jpg\" loading=\"lazy\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-26.jpg 1920w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-26-300x200.jpg 300w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-26-1024x681.jpg 1024w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-26-768x511.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-26-1536x1022.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" alt=\"Deglava Rezidence - new apartments in Riga\">\n<\/div>\n<\/div>\n<\/div><div class=\"bde-video-30-1685 bde-video stagger-item\">\n<div class=\"ee-video-container\">\n            <video class=\"ee-video\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/04\/Deglava-Rezidence.mp4\"\n                               controls='true'                                                                controlslist=\"nodownload\"                playsinline\n>\n        <\/video>\n    \n    <\/div>\n\n<\/div><\/div>\n<\/section><section class=\"bde-section-30-1296 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-div-30-1297 bde-div silky-reveal\" data-parallax=\"true\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-30-1306 bde-image2 img-reveal\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/logo_electra_25_01_2021.png\" loading=\"lazy\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/logo_electra_25_01_2021.png 400w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/logo_electra_25_01_2021-300x298.png 300w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/logo_electra_25_01_2021-150x150.png 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" alt=\"Deglava Rezidence - new apartments in Riga\"><div class=\"bde-div-30-1299 bde-div\">\n  \n  \n\t\n\n\n\n<p class=\"bde-text-30-1320 bde-text stagger-item\">\nDeveloper\n<\/p><h3 class=\"bde-heading-30-1319 bde-heading stagger-item\">\nElectra Group - in a Glance\n<\/h3><div class=\"bde-fancy-divider-30-1301 bde-fancy-divider stagger-item\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-div-30-1302 bde-div\">\n  \n  \n\t\n\n\n\n<p class=\"bde-text-30-1303 bde-text stagger-item\">\nOver the past seventy years, the Electra Group has built up invaluable experience and a reputation as a global business leader. The Group's international portfolio includes projects of all complexities, currently spanning 17 countries on 4 continents.<br><br>Founded in 1945 and listed on the Tel Aviv Stock Exchange since 1971, Electra operates with a multi-level approach and exploits the unique synergies that exist between its subsidiaries.\n<\/p><div class=\"bde-button-30-1304 bde-button stagger-item\">\n        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--text bde-button__button\" href=\"\/en\/team\/\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Read more<\/span>\n\n        \n                    \n    <span class=\"button-atom__icon-wrapper\">\n\n        \n            <svg class=\"un-arrow-icon\" width=\"10\" height=\"10\" viewbox=\"0 0 10 10\" aria-hidden=\"true\">\n                <g fill-rule=\"evenodd\">\n                    <path class=\"un-arrow-icon_arrow\" d=\"M1 1l4 4-4 4\"><\/path>\n                <\/g>\n            <\/svg>\n\n        \n    <\/span>\n\n\n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"bde-div-30-1321 bde-div silky-reveal\" data-parallax=\"true\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-30-1322 bde-image2 img-reveal\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/RietumuBanka_SquareGradient-640x640-1.png\" alt=\"Rietumu banka, Deglava Residence\" loading=\"lazy\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/RietumuBanka_SquareGradient-640x640-1.png 640w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/RietumuBanka_SquareGradient-640x640-1-300x300.png 300w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/RietumuBanka_SquareGradient-640x640-1-150x150.png 150w\" sizes=\"(max-width: 640px) 100vw, 640px\"><div class=\"bde-div-30-1323 bde-div\">\n  \n  \n\t\n\n\n\n<p class=\"bde-text-30-1324 bde-text stagger-item\">\nFunder\n<\/p><h3 class=\"bde-heading-30-1325 bde-heading stagger-item\">\nRietumu Banka\n<\/h3><div class=\"bde-fancy-divider-30-1326 bde-fancy-divider stagger-item\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-div-30-1327 bde-div\">\n  \n  \n\t\n\n\n\n<p class=\"bde-text-30-1328 bde-text stagger-item\">\nWestern. A bank for Latvian business that appreciates nuance.<br><br>Rietumu Banka is the largest local capital bank in Latvia with more than 30 years of successful experience. Its activities are focused on servicing large and medium-sized Latvian and Baltic companies.\n<\/p><div class=\"bde-button-30-1329 bde-button stagger-item\">\n        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--text bde-button__button\" href=\"\/en\/team\/\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Read more<\/span>\n\n        \n                    \n    <span class=\"button-atom__icon-wrapper\">\n\n        \n            <svg class=\"un-arrow-icon\" width=\"10\" height=\"10\" viewbox=\"0 0 10 10\" aria-hidden=\"true\">\n                <g fill-rule=\"evenodd\">\n                    <path class=\"un-arrow-icon_arrow\" d=\"M1 1l4 4-4 4\"><\/path>\n                <\/g>\n            <\/svg>\n\n        \n    <\/span>\n\n\n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/section><section class=\"bde-section-30-1331 bde-section silky-reveal\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-heading-30-1662 bde-heading stagger-item\">\nChoose a house\n<\/h2><div class=\"bde-globalblock-30-1661 bde-globalblock\"><div class=\"bde-grid-1073-100-1073-1 bde-grid bde-grid-1073-100\">\n  \n  \n\t\n\n\n\n<a class=\"bde-container-link-1073-101-1073-1 bde-container-link hause-card stagger-item bde-container-link-1073-101 breakdance-link\" href=\"\/en\/dali-table\/\" target=\"_self\" data-type=\"url\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-1073-102-1073-1 bde-div bde-div-1073-102\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-1073-103-1073-1 bde-image2 hause-card-img bde-image2-1073-103\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Dali.jpg\" alt=\"Dali\" loading=\"lazy\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Dali.jpg 1600w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Dali-300x300.jpg 300w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Dali-1024x1024.jpg 1024w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Dali-150x150.jpg 150w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Dali-768x768.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Dali-1536x1536.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" data-entrance=\"fade\">\n<\/div><div class=\"bde-div-1073-104-1073-1 bde-div bde-div-1073-104\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-1073-105-1073-1 bde-div bde-div-1073-105\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1073-106-1073-1 bde-heading stagger-item bde-heading-1073-106\">\nDali\n<\/h4><div class=\"bde-div-1073-127-1073-1 bde-div bde-div-1073-127\">\n  \n  \n\t\n\n\n\n<div class=\"bde-text-1073-107-1073-1 bde-text stagger-item bde-text-1073-107\">\nBuilding 5 | 71 apartments\n<\/div><div class=\"bde-text-1073-126-1073-1 bde-text stagger-item bde-text-1073-126\">\n| Available \n<\/div><div class=\"bde-text-1073-132-1073-1 bde-text stagger-item bde-text-1073-132\">\n10\n<\/div>\n<\/div>\n<\/div><div class=\"bde-button-1073-108-1073-1 bde-button stagger-item bde-button-1073-108\">\n        \n    \n    \n    \n    \n            \n            <button type=\"button\" class=\"button-atom button-atom--custom button-atom--preset-43d98a18-5478-430f-b9a5-b09eb9e462ff bde-button__button\"  >\n    \n        <span class=\"button-atom__text\">View<\/span>\n\n        \n        \n            <\/button>\n    \n\n\n<\/div>\n<\/div>\n\n<\/a><a class=\"bde-container-link-1073-109-1073-1 bde-container-link hause-card stagger-item bde-container-link-1073-109 breakdance-link\" href=\"https:\/\/deglavarezidence.lv\/en\/rembrandt-building-6\/\" target=\"_self\" data-type=\"url\" data-entrance=\"slideUp\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-1073-110-1073-1 bde-div bde-div-1073-110\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-1073-111-1073-1 bde-image2 hause-card-img bde-image2-1073-111\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Rebrandt.jpg\" alt=\"Rebrandt\" loading=\"lazy\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Rebrandt.jpg 1600w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Rebrandt-300x300.jpg 300w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Rebrandt-1024x1024.jpg 1024w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Rebrandt-150x150.jpg 150w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Rebrandt-768x768.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Rebrandt-1536x1536.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" data-entrance=\"fade\">\n<\/div><div class=\"bde-div-1073-112-1073-1 bde-div bde-div-1073-112\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-1073-113-1073-1 bde-div bde-div-1073-113\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1073-114-1073-1 bde-heading stagger-item bde-heading-1073-114\">\nRembrandt\n<\/h4><div class=\"bde-div-1073-128-1073-1 bde-div bde-div-1073-128\">\n  \n  \n\t\n\n\n\n<div class=\"bde-text-1073-115-1073-1 bde-text stagger-item bde-text-1073-115\">\nBuilding 6 | 78 apartments\n<\/div><div class=\"bde-text-1073-129-1073-1 bde-text stagger-item bde-text-1073-129\">\n| Available \n<\/div><div class=\"bde-text-1073-133-1073-1 bde-text stagger-item bde-text-1073-133\">\n68\n<\/div>\n<\/div>\n<\/div><div class=\"bde-button-1073-116-1073-1 bde-button stagger-item bde-button-1073-116\">\n        \n    \n    \n    \n    \n            \n            <button type=\"button\" class=\"button-atom button-atom--custom button-atom--preset-43d98a18-5478-430f-b9a5-b09eb9e462ff bde-button__button\"  >\n    \n        <span class=\"button-atom__text\">View<\/span>\n\n        \n        \n            <\/button>\n    \n\n\n<\/div>\n<\/div>\n\n<\/a><a class=\"bde-container-link-1073-117-1073-1 bde-container-link hause-card stagger-item bde-container-link-1073-117 breakdance-link\" href=\"https:\/\/deglavarezidence.lv\/en\/picasso-building-7\/\" target=\"_self\" data-type=\"url\" data-entrance=\"slideUp\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-1073-118-1073-1 bde-div bde-div-1073-118\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-1073-119-1073-1 bde-image2 hause-card-img bde-image2-1073-119\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Picasso.jpg\" alt=\"Picasso\" loading=\"lazy\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Picasso.jpg 1600w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Picasso-300x300.jpg 300w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Picasso-1024x1024.jpg 1024w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Picasso-150x150.jpg 150w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Picasso-768x768.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/02\/Picasso-1536x1536.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" data-entrance=\"fade\">\n<\/div><div class=\"bde-div-1073-120-1073-1 bde-div bde-div-1073-120\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-1073-121-1073-1 bde-div bde-div-1073-121\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1073-122-1073-1 bde-heading stagger-item bde-heading-1073-122\">\nPicasso\n<\/h4><div class=\"bde-div-1073-131-1073-1 bde-div bde-div-1073-131\">\n  \n  \n\t\n\n\n\n<div class=\"bde-text-1073-123-1073-1 bde-text stagger-item bde-text-1073-123\">\nBuilding 7 | 78 apartments\n<\/div><div class=\"bde-text-1073-130-1073-1 bde-text stagger-item bde-text-1073-130\">\n| Available \n<\/div><div class=\"bde-text-1073-134-1073-1 bde-text stagger-item bde-text-1073-134\">\n48\n<\/div>\n<\/div>\n<\/div><div class=\"bde-button-1073-124-1073-1 bde-button stagger-item bde-button-1073-124\">\n        \n    \n    \n    \n    \n            \n            <button type=\"button\" class=\"button-atom button-atom--custom button-atom--preset-43d98a18-5478-430f-b9a5-b09eb9e462ff bde-button__button\"  >\n    \n        <span class=\"button-atom__text\">View<\/span>\n\n        \n        \n            <\/button>\n    \n\n\n<\/div>\n<\/div>\n\n<\/a>\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-30-1553 bde-section silky-reveal\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-heading-30-1554 bde-heading\">\nProject description\n<\/h2><div class=\"bde-grid-30-1635 bde-grid\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-30-1636 bde-image2 img-reveal\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-scaled.jpg\" loading=\"lazy\" srcset=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-scaled.jpg 2560w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-300x169.jpg 300w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-1024x576.jpg 1024w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-768x432.jpg 768w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-1536x864.jpg 1536w, https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Deglava-Rezidence-2048x1152.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" alt=\"Deglava Rezidence - new apartments in Riga\"><div class=\"bde-div-30-1637 bde-div stagger-item\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-30-1638 bde-div bde-preset-deee2cbe-38af-47a7-8c10-be75d6a8b9b7\" data-parallax=\"true\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-30-1639 bde-image2 bde-preset-7f03b89b-04cb-4319-8950-754af957e2dd\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Frame-8.svg\" loading=\"lazy\" alt=\"Deglava Rezidence - new apartments in Riga\">\n<\/div><div class=\"bde-text-30-1640 bde-text\" data-parallax=\"true\">\nTotal of 521 new 1-4 bedroom apartments\n<\/div>\n<\/div><div class=\"bde-div-30-1641 bde-div stagger-item\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-30-1642 bde-div bde-preset-deee2cbe-38af-47a7-8c10-be75d6a8b9b7\" data-parallax=\"true\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-30-1643 bde-image2 bde-preset-7f03b89b-04cb-4319-8950-754af957e2dd\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Frame-6.svg\" loading=\"lazy\" alt=\"Deglava Rezidence - new apartments in Riga\">\n<\/div><div class=\"bde-text-30-1644 bde-text\" data-parallax=\"true\">\nGround parking, storage\n<\/div>\n<\/div><div class=\"bde-div-30-1645 bde-div stagger-item\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-30-1646 bde-div bde-preset-deee2cbe-38af-47a7-8c10-be75d6a8b9b7\" data-parallax=\"true\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-30-1647 bde-image2 bde-preset-7f03b89b-04cb-4319-8950-754af957e2dd\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Bernu-laukums-1.svg\" loading=\"lazy\" alt=\"Deglava Rezidence - new apartments in Riga\">\n<\/div><div class=\"bde-text-30-1648 bde-text\" data-parallax=\"true\">\nChildren's playgrounds and sports areas\n<\/div>\n<\/div><div class=\"bde-div-30-1649 bde-div stagger-item\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-30-1650 bde-div bde-preset-deee2cbe-38af-47a7-8c10-be75d6a8b9b7\" data-parallax=\"true\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-30-1651 bde-image2 bde-preset-7f03b89b-04cb-4319-8950-754af957e2dd\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Frame-4.svg\" loading=\"lazy\" alt=\"Deglava Rezidence - new apartments in Riga\">\n<\/div><div class=\"bde-text-30-1652 bde-text\" data-parallax=\"true\">\nDeveloped infra infrastructure\n<\/div>\n<\/div><div class=\"bde-div-30-1653 bde-div stagger-item\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-30-1654 bde-div bde-preset-deee2cbe-38af-47a7-8c10-be75d6a8b9b7\" data-parallax=\"true\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-30-1655 bde-image2 bde-preset-7f03b89b-04cb-4319-8950-754af957e2dd\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Frame-2-1.svg\" loading=\"lazy\" alt=\"Deglava Rezidence - new apartments in Riga\">\n<\/div><div class=\"bde-text-30-1656 bde-text\" data-parallax=\"true\">\nGreen areas\n<\/div>\n<\/div><div class=\"bde-div-30-1657 bde-div stagger-item\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-30-1658 bde-div bde-preset-deee2cbe-38af-47a7-8c10-be75d6a8b9b7\" data-parallax=\"true\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-30-1659 bde-image2 bde-preset-7f03b89b-04cb-4319-8950-754af957e2dd\" src=\"https:\/\/deglavarezidence.lv\/wp-content\/uploads\/2026\/01\/Frame-3.svg\" loading=\"lazy\" alt=\"Deglava Rezidence - new apartments in Riga\">\n<\/div><div class=\"bde-text-30-1660 bde-text\" data-parallax=\"true\">\nClosed area with video surveillance\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Deglava Gleznot\u0101ju rezidence \u2014 vieta, kur tava dz\u012bve p\u0101rtop par m\u0101kslas darbu. Dz\u012bvok\u013ci ar pilnu apdari un A energoefektivit\u0101ti. Gatavi dz\u012bvo\u0161anai jau \u0161odien. Cena no 67 821 \u20ac Izv\u0113l\u0113ties dz\u012bvokli Piesaki apskati Par projektu Laipni l\u016bgti m\u0101j\u0101s, P\u013cavnieku sird\u012b esam uzgleznoju\u0161i jaunu ainu \u2013 Deglava Gleznot\u0101ju rezidenci \u2013 m\u016bsdien\u012bgu jaunu projektu.Jaunais projekts sniedz visu, kas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_breakdance_hide_in_design_set":false,"_breakdance_tags":"","footnotes":""},"class_list":["post-30","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/deglavarezidence.lv\/en\/wp-json\/wp\/v2\/pages\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deglavarezidence.lv\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/deglavarezidence.lv\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/deglavarezidence.lv\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/deglavarezidence.lv\/en\/wp-json\/wp\/v2\/comments?post=30"}],"version-history":[{"count":0,"href":"https:\/\/deglavarezidence.lv\/en\/wp-json\/wp\/v2\/pages\/30\/revisions"}],"wp:attachment":[{"href":"https:\/\/deglavarezidence.lv\/en\/wp-json\/wp\/v2\/media?parent=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}